{"id":4646,"date":"2026-05-13T10:29:06","date_gmt":"2026-05-13T09:29:06","guid":{"rendered":"https:\/\/espaciolaplaza.es\/?p=4646"},"modified":"2026-05-13T10:29:06","modified_gmt":"2026-05-13T09:29:06","slug":"los-corrales-de-buelna-acoge-una-jornada-conmemorativa-por-el-dia-internacional-de-las-vasculitis","status":"publish","type":"post","link":"https:\/\/espaciolaplaza.es\/index.php\/2026\/05\/13\/los-corrales-de-buelna-acoge-una-jornada-conmemorativa-por-el-dia-internacional-de-las-vasculitis\/","title":{"rendered":"Los Corrales de Buelna acoge una jornada conmemorativa por el D\u00eda Internacional de las Vasculitis"},"content":{"rendered":"<p data-start=\"103\" data-end=\"434\">El Aula de Cultura La Plaza de <strong data-start=\"134\" data-end=\"175\"><span class=\"hover:entity-accent entity-underline inline cursor-pointer align-baseline\"><span class=\"whitespace-normal\">Los Corrales de Buelna<\/span><\/span><\/strong> acoger\u00e1 este <strong data-start=\"195\" data-end=\"234\">s\u00e1bado 16 de mayo a las 17:00 horas<\/strong> un acto de conmemoraci\u00f3n del <strong data-start=\"264\" data-end=\"303\">D\u00eda Internacional de las Vasculitis<\/strong>, una jornada organizada para dar visibilidad a esta enfermedad y concienciar sobre la importancia de su diagn\u00f3stico y tratamiento.<\/p>\n<p data-start=\"436\" data-end=\"718\">El encuentro contar\u00e1 con una mesa institucional en la que participar\u00e1n representantes sanitarios y municipales, entre ellos miembros de la Consejer\u00eda de Salud, responsables del Hospital Universitario Marqu\u00e9s de Valdecilla y representantes del Ayuntamiento de Los Corrales de Buelna.<\/p>\n<p data-start=\"720\" data-end=\"1176\">Adem\u00e1s, la programaci\u00f3n incluir\u00e1 una mesa de ponentes formada por profesionales del \u00e1mbito m\u00e9dico, psicol\u00f3gico y social. Entre ellos participar\u00e1n el reumat\u00f3logo <strong data-start=\"881\" data-end=\"922\"><span class=\"hover:entity-accent entity-underline inline cursor-pointer align-baseline\"><span class=\"whitespace-normal\">Julio S\u00e1nchez<\/span><\/span><\/strong>, la psiquiatra <strong data-start=\"938\" data-end=\"979\"><span class=\"hover:entity-accent entity-underline inline cursor-pointer align-baseline\"><span class=\"whitespace-normal\">Paola Alejandra Hern\u00e1ndez<\/span><\/span><\/strong> y la trabajadora social <strong data-start=\"1004\" data-end=\"1045\"><span class=\"hover:entity-accent entity-underline inline cursor-pointer align-baseline\"><span class=\"whitespace-normal\">Ruth Balza Iglesias<\/span><\/span><\/strong>, quienes abordar\u00e1n distintos aspectos relacionados con las vasculitis y el impacto de esta enfermedad en la vida de los pacientes.<\/p>\n<p data-start=\"1178\" data-end=\"1414\" data-is-last-node=\"\" data-is-only-node=\"\">La jornada pretende convertirse en un espacio de informaci\u00f3n, apoyo y sensibilizaci\u00f3n, fomentando el conocimiento sobre una patolog\u00eda poco frecuente y reforzando la importancia de la atenci\u00f3n sanitaria y social a las personas afectadas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Aula de Cultura La Plaza de Los Corrales de Buelna acoger\u00e1 este s\u00e1bado 16 de mayo a las 17:00 horas un acto de conmemoraci\u00f3n del D\u00eda Internacional de las Vasculitis, una jornada organizada para dar visibilidad a esta enfermedad y concienciar sobre la importancia de su diagn\u00f3stico y tratamiento. El encuentro contar\u00e1 con una [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":4643,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[1328,1333,1326,1330,58,614,104,1324,1332,83,1329,1325,17,1327,1197,1331,409],"_links":{"self":[{"href":"https:\/\/espaciolaplaza.es\/index.php\/wp-json\/wp\/v2\/posts\/4646"}],"collection":[{"href":"https:\/\/espaciolaplaza.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espaciolaplaza.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espaciolaplaza.es\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/espaciolaplaza.es\/index.php\/wp-json\/wp\/v2\/comments?post=4646"}],"version-history":[{"count":1,"href":"https:\/\/espaciolaplaza.es\/index.php\/wp-json\/wp\/v2\/posts\/4646\/revisions"}],"predecessor-version":[{"id":4647,"href":"https:\/\/espaciolaplaza.es\/index.php\/wp-json\/wp\/v2\/posts\/4646\/revisions\/4647"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espaciolaplaza.es\/index.php\/wp-json\/wp\/v2\/media\/4643"}],"wp:attachment":[{"href":"https:\/\/espaciolaplaza.es\/index.php\/wp-json\/wp\/v2\/media?parent=4646"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espaciolaplaza.es\/index.php\/wp-json\/wp\/v2\/categories?post=4646"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espaciolaplaza.es\/index.php\/wp-json\/wp\/v2\/tags?post=4646"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}