{"id":1323,"count":2,"description":"","link":"https:\/\/espaciolaplaza.es\/index.php\/tag\/filmoteca-mayo\/","name":"filmoteca mayo","slug":"filmoteca-mayo","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/espaciolaplaza.es\/index.php\/wp-json\/wp\/v2\/tags\/1323"}],"collection":[{"href":"https:\/\/espaciolaplaza.es\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/espaciolaplaza.es\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/espaciolaplaza.es\/index.php\/wp-json\/wp\/v2\/posts?tags=1323"},{"href":"https:\/\/espaciolaplaza.es\/index.php\/wp-json\/wp\/v2\/mec-events?tags=1323"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}