{"id":1338,"count":2,"description":"","link":"https:\/\/espaciolaplaza.es\/index.php\/tag\/50-aniversario\/","name":"50 aniversario","slug":"50-aniversario","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/espaciolaplaza.es\/index.php\/wp-json\/wp\/v2\/tags\/1338"}],"collection":[{"href":"https:\/\/espaciolaplaza.es\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/espaciolaplaza.es\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/espaciolaplaza.es\/index.php\/wp-json\/wp\/v2\/posts?tags=1338"},{"href":"https:\/\/espaciolaplaza.es\/index.php\/wp-json\/wp\/v2\/mec-events?tags=1338"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}