{"id":1343,"count":2,"description":"","link":"https:\/\/espaciolaplaza.es\/index.php\/tag\/amigos-de-la-biblioteca\/","name":"Amigos de la Biblioteca","slug":"amigos-de-la-biblioteca","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/espaciolaplaza.es\/index.php\/wp-json\/wp\/v2\/tags\/1343"}],"collection":[{"href":"https:\/\/espaciolaplaza.es\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/espaciolaplaza.es\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/espaciolaplaza.es\/index.php\/wp-json\/wp\/v2\/posts?tags=1343"},{"href":"https:\/\/espaciolaplaza.es\/index.php\/wp-json\/wp\/v2\/mec-events?tags=1343"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}